{"id":6372,"date":"2024-12-04T20:32:47","date_gmt":"2024-12-04T19:32:47","guid":{"rendered":"https:\/\/discoversoller.com\/butxet\/"},"modified":"2025-03-06T14:30:50","modified_gmt":"2025-03-06T13:30:50","slug":"butxet","status":"publish","type":"page","link":"https:\/\/discoversoller.com\/es\/butxet\/","title":{"rendered":"Bodega Butxet. Muro, Islas Baleares."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6372\" class=\"elementor elementor-6372 elementor-4183\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0137f9 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"d0137f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a5b2ba elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"1a5b2ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;speed&quot;:655,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/67.jpg\" alt=\"Bodega Butxet: tradition, passion, and innovation poured into every bottle of their Mallorcan wines.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/64.jpg\" alt=\"Bodega Butxet: tradition, passion, and innovation poured into every bottle of their Mallorcan wines.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/7f.jpg\" alt=\"Bodega Butxet: a sensory journey into Mallorca\u2019s heart through its distinctive wines.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/6e.jpg\" alt=\"Bodega Butxet: premium wines that blend the character of Mallorca with artisanal craftsmanship.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/6c.jpg\" alt=\"Bodega Butxet: a showcase of Mallorcan winemaking excellence, reflecting the land&#039;s essence in every bottle.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/6b.jpg\" alt=\"Bodega Butxet: a hidden gem in Mallorca, producing exceptional wines from local grapes with passion.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/5e.jpg\" alt=\"Bodega Butxet: where tradition meets innovation, crafting unique wines with authentic Mallorcan flavor.\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2fad35 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"b2fad35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d91881b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d91881b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91175e7 elementor-widget elementor-widget-heading\" data-id=\"91175e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BUTXET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e20776f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e20776f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c39a3f2 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"c39a3f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60f326c elementor-widget elementor-widget-text-editor\" data-id=\"60f326c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nuestra bodega est\u00e1 situada en el pol\u00edgono 12, parcela 565 de Muro, en la finca Son Morei, justo en el l\u00edmite del vi\u00f1edo.<\/strong><\/p>\n<p><strong>Est\u00e1 situado a s\u00f3lo 800 metros del inicio del parque natural de la Albufera de Muro, y a unos 4 kil\u00f3metros del mar, desde Platja de Muro.<\/strong><\/p>\n<p><strong>Producimos vinos tintos, blancos y rosados, todos ellos elaborados con uvas procedentes de nuestros propios vi\u00f1edos.<\/strong><\/p>\n<p><strong>Trabajamos con variedades internacionales como Cabernet Sauvignon, Merlot, Syrah y Chardonnay, as\u00ed como con variedades aut\u00f3ctonas como Giro Ros, Premsal, Mantonegro, Callet y Escursac.<\/strong><\/p>\n<p><strong>Todos ellos se plantan en diversas parcelas seg\u00fan el suelo y el microclima de cada parcela.<\/strong><\/p>\n<p><strong>El resultado es una diversa gama de vinos, muy influenciados por su ubicaci\u00f3n, ya que est\u00e1n situados a pocos metros de la Albufera de Muro y cerca del mar, lo que confiere a los vinos una singularidad especial.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2492399 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2492399\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48464f5 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"48464f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-356b989 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"356b989\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d09436d elementor-widget elementor-widget-image\" data-id=\"d09436d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-768x1024.jpg\" class=\"attachment-large size-large wp-image-6357\" alt=\"Bodega Butxet: tradition, passion, and innovation poured into every bottle of their Mallorcan wines.\" srcset=\"https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-768x1024.jpg 768w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-225x300.jpg 225w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-1152x1536.jpg 1152w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-1536x2048.jpg 1536w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-1440x1920.jpg 1440w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-600x800.jpg 600w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-800x1067.jpg 800w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-380x507.jpg 380w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-247x330.jpg 247w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-278x371.jpg 278w, https:\/\/discoversoller.com\/wp-content\/uploads\/2024\/12\/IMG_1035-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9031dfd e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"9031dfd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-66e02b8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"66e02b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c539074 elementor-widget elementor-widget-text-editor\" data-id=\"c539074\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>DESCRIPCI\u00d3N GENERAL<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5884f6e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5884f6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b83c97 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"6b83c97\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63567be elementor-widget elementor-widget-text-editor\" data-id=\"63567be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Comenzar\u00e1 esta <strong>experiencia<\/strong> visitando parte de los vi\u00f1edos y descubriendo curiosidades sobre la zona en la que se encuentra la bodega. A continuaci\u00f3n, podr\u00e1 ver y conocer el proceso de elaboraci\u00f3n del vino. La visita finalizar\u00e1 con una degustaci\u00f3n de 5 vinos acompa\u00f1ados de dos <strong>tapas t\u00edpicas mallorquinas<\/strong>. Se trata de una empresa familiar situada en la parte norte de Mallorca, justo detr\u00e1s del Parque Natural de la Albufera. Dado que las uvas se cultivan casi a nivel del mar, los vinos producidos tienen unas cualidades \u00fanicas y f\u00e1ciles de beber.    <\/p>\n<p>En nuestras bodegas, explorar\u00e1s<strong> vi\u00f1edos con variedades de uva tanto locales como internacionales<\/strong> que han sido reconocidas con varios premios nacionales e internacionales gracias al arduo trabajo y compromiso de sus cuidadores. La visita a la bodega combina caracter\u00edsticas ideales al mezclar el buen clima con la riqueza del vino mallorqu\u00edn de una manera verdaderamente incomparable y apasionada. <span style=\"text-decoration: underline;\"><strong>Elaboramos vinos con mucha personalidad, haciendo de tu visita algo \u00fanico.<\/strong><\/span>  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b53459 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"5b53459\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-10e0606 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"10e0606\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08ca896 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"08ca896\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hourglass\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t2 Horas (Aprox...)\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94c473b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"94c473b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d49d7ee elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d49d7ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-comments\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIdiomas: Ingl\u00e9s y espa\u00f1ol\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee9dead e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"ee9dead\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23a3e38 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"23a3e38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-money-bill-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tA partir de 20\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-257f0eb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"257f0eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6093c9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e6093c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-flag\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBodega Butxet Carretera de Muro a Can Picafort Km 330, parcela 565, 07440, Islas Baleares, Espa\u00f1a\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d251fb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"8d251fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17c8f5c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"17c8f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-stopwatch\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tHora de inicio: 15:30\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-714251f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"714251f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c55b8f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8c55b8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-413a394 elementor-widget elementor-widget-heading\" data-id=\"413a394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HAGA SU RESERVA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbc3cd2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bbc3cd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-544e6fb e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"544e6fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-894370c elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"894370c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Siguiente&quot;,&quot;step_previous_label&quot;:&quot;Anterior&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuevo formulario\" aria-label=\"Nuevo formulario\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"6372\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"894370c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Bodega Butxet. Muro, Islas Baleares. - Discover S\u00f3ller\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"6372\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNOMBRE COMPLETO\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"NOMBRE COMPLETO\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_54de01a elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_54de01a\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tN\u00daMERO DE TEL\u00c9FONO\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_54de01a]\" id=\"form-field-field_54de01a\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"N\u00daMERO DE TEL\u00c9FONO\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_08cf502 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_08cf502\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tFecha\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_08cf502]\" id=\"form-field-field_08cf502\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Fecha \">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_7c19323 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_7c19323\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tHorario\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_7c19323]\" id=\"form-field-field_7c19323\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"A que hora le gustar\u00eda venir?\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_3792688 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3792688\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tN\u00famero de personas\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_3792688]\" id=\"form-field-field_3792688\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"N\u00famero de personas\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_1cce48a elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_1cce48a\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMensaje\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_1cce48a]\" id=\"form-field-field_1cce48a\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Comentarios\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Env\u00eda<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>BUTXET Nuestra bodega est\u00e1 situada en el pol\u00edgono 12, parcela 565 de Muro, en la finca Son Morei, justo en el l\u00edmite del vi\u00f1edo. Est\u00e1 situado a s\u00f3lo 800 metros del inicio del parque natural de la Albufera de Muro, y a unos 4 kil\u00f3metros del mar, desde Platja de Muro. Producimos vinos tintos, blancos y rosados, todos ellos elaborados con uvas procedentes de nuestros propios vi\u00f1edos. Trabajamos con variedades internacionales como Cabernet Sauvignon, Merlot, Syrah y Chardonnay, as\u00ed como con variedades aut\u00f3ctonas como Giro Ros, Premsal, Mantonegro, Callet y Escursac. Todos ellos se plantan en diversas parcelas seg\u00fan el suelo y el microclima de cada parcela. El resultado es una diversa gama de vinos, muy influenciados por su ubicaci\u00f3n, ya que est\u00e1n situados a pocos metros de la Albufera de Muro y cerca del mar, lo que confiere a los vinos una singularidad especial. DESCRIPCI\u00d3N GENERAL Comenzar\u00e1 esta experiencia visitando parte de los vi\u00f1edos y descubriendo curiosidades sobre la zona en la que se encuentra la bodega. A continuaci\u00f3n, podr\u00e1 ver y conocer el proceso de elaboraci\u00f3n del vino. La visita finalizar\u00e1 con una degustaci\u00f3n de 5 vinos acompa\u00f1ados de dos tapas t\u00edpicas mallorquinas. Se trata de una empresa familiar situada en la parte norte de Mallorca, justo detr\u00e1s del Parque Natural de la Albufera. Dado que las uvas se cultivan casi a nivel del mar, los vinos producidos tienen unas cualidades \u00fanicas y f\u00e1ciles de beber. En nuestras bodegas, explorar\u00e1s vi\u00f1edos con variedades de uva tanto locales como internacionales que han sido reconocidas con varios premios nacionales e internacionales gracias al arduo trabajo y compromiso de sus cuidadores. La visita a la bodega combina caracter\u00edsticas ideales al mezclar el buen clima con la riqueza del vino mallorqu\u00edn de una manera verdaderamente incomparable y apasionada. Elaboramos vinos con mucha personalidad, haciendo de tu visita algo \u00fanico. 2 Horas (Aprox&#8230;) Idiomas: Ingl\u00e9s y espa\u00f1ol A partir de 20 Bodega Butxet Carretera de Muro a Can Picafort Km 330, parcela 565, 07440, Islas Baleares, Espa\u00f1a Hora de inicio: 15:30 HAGA SU RESERVA<\/p>\n","protected":false},"author":3,"featured_media":6357,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-6372","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/pages\/6372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/comments?post=6372"}],"version-history":[{"count":6,"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/pages\/6372\/revisions"}],"predecessor-version":[{"id":9392,"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/pages\/6372\/revisions\/9392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/media\/6357"}],"wp:attachment":[{"href":"https:\/\/discoversoller.com\/es\/wp-json\/wp\/v2\/media?parent=6372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}